{"id":29214,"date":"2026-07-15T19:30:41","date_gmt":"2026-07-15T17:30:41","guid":{"rendered":"https:\/\/www.mio.osupytheas.fr\/?p=29214"},"modified":"2026-07-15T20:02:45","modified_gmt":"2026-07-15T18:02:45","slug":"these-eleonord-mayissah-moungues","status":"publish","type":"post","link":"https:\/\/www.mio.osupytheas.fr\/en\/these-eleonord-mayissah-moungues\/","title":{"rendered":"Eleonord Mayissah Moungues will defend his thesis on Friday 17 July 2026 at 2.00 pm \u2013 University of Toulon \u2013 La Garde Campus \u2013 Building Y1 \u2013 Lecture Theatre Y1.018"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29214\" class=\"elementor elementor-29214\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85a7d7d e-flex e-con-boxed e-con e-parent\" data-id=\"85a7d7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fe8cae elementor-widget elementor-widget-text-editor\" data-id=\"1fe8cae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\"><strong>Eleonord Mayissah Moungues<\/strong> (Universit\u00e9 des Sciences et Techniques de Masuku USTM Gabo &#8211; MIO Universit\u00e9 de Toulon) soutiendra sa th\u00e8se de doctorat le <strong>Vendredi 17 juillet 2026<\/strong> \u00e0 <strong>14h00<\/strong> \u00e0 l&#8217;Universit\u00e9 de Toulon &#8211; Campus La Garde &#8211; B\u00e2timent Y1 \u2013 Amphi Y1.018,\u00a0 sur le sujet suivant : <em>Les apports chimiques et microbiologiques du fleuve Ogoou\u00e9 sur ses mangroves. <\/em><\/p><p style=\"text-align: justify;\"><strong>Watching the defence via videoconference: <\/strong><a href=\"https:\/\/ird-fr.zoom.us\/j\/95658918911?pwd=LEROYzJW7gtM0yN5KYw5d3batYL0gx.1\" target=\"_blank\" rel=\"noopener\"><strong>Zoom link<\/strong><\/a><\/p><h4 style=\"text-align: justify;\">\u00a0<\/h4><h4 style=\"text-align: justify;\"><strong>Abstract<\/strong><\/h4><p style=\"text-align: justify;\">Les s\u00e9diments des rivi\u00e8res et des mangroves agissent comme le r\u00e9servoir \u00e9cologique, ils accumulent les m\u00e9taux issus de l&#8217;activit\u00e9 humaine (mines, industries, agriculture, villes). Mais ce pi\u00e9geage n&#8217;est pas fig\u00e9. Quand les conditions changent : climat, mar\u00e9es, dragage. Ces m\u00e9taux peuvent \u00eatre rel\u00e2ch\u00e9s dans l&#8217;eau, contaminer les poissons et, \u00e0 terme, remonter jusqu&#8217;\u00e0 notre assiette.<\/p><p style=\"text-align: justify;\">Au Gabon, le fleuve Ogoou\u00e9 traverse pr\u00e9cis\u00e9ment ce type de situation : il prend naissance dans une zone mini\u00e8re (mangan\u00e8se, or), traverse des zones rurales et urbaines, puis se jette dans l&#8217;oc\u00e9an Atlantique, alimentant l&#8217;une des plus grandes mangroves d&#8217;Afrique centrale. Tout au long de ce parcours, les pressions humaines changent et le fleuve draine de nombreuses particules s\u00e9dimentaires, potentiellement contamin\u00e9es. Toutefois, bien qu&#8217;utile, le suivi environnemental existant repose surtout sur des images satellites et des mesures chimiques ponctuelles qui ne signalent les dommages qu&#8217;une fois qu&#8217;ils sont d\u00e9j\u00e0 visibles.<\/p><p style=\"text-align: justify;\">Cette th\u00e8se propose une autre approche combinant les indicateurs g\u00e9ochimiques classiques et les communaut\u00e9s microbiennes qui vivent dans les s\u00e9diments (bact\u00e9ries, arch\u00e9es), invisibles \u00e0 l&#8217;\u0153il nu, elles sont pr\u00e9sentes par milliards dans chaque gramme de vase. Ces microorganismes r\u00e9agissent tr\u00e8s vite aux changements de leur environnement : Par exemple, si un contaminant, notamment m\u00e9tallique, augmente, certains microorganismes disparaissent, d&#8217;autres prolif\u00e8rent. Lire ces changements de communaut\u00e9s microbiennes permettrait d&#8217;ajouter un outil de surveillance compl\u00e9mentaire pour les gestionnaires.<br \/>En \u00e9tudiant trois zones du fleuve Ogoou\u00e9, la r\u00e9gion mini\u00e8re de Franceville-Moanda en amont, le cours principal de l&#8217;Ogoou\u00e9, et les mangroves de Port-Gentil sur la c\u00f4te, ce travail montre que la combinaison d&#8217;indicateurs g\u00e9ochimiques et d&#8217;indicateurs microbiens donne une image bien plus fine et plus pr\u00e9coce de l&#8217;\u00e9tat des \u00e9cosyst\u00e8mes.<\/p><p style=\"text-align: justify;\">Cette th\u00e8se propose des outils concrets aux gestionnaires environnementaux leur permettant d&#8217;anticiper les d\u00e9gradations plut\u00f4t que de les constater Cette d\u00e9marche est transf\u00e9rable \u00e0 d&#8217;autres pays confront\u00e9s aux m\u00eames d\u00e9fis : concilier d\u00e9veloppement \u00e9conomique, exploitation des ressources et protection d&#8217;un patrimoine naturel.<\/p><h4 style=\"text-align: justify;\"><strong>Key words<\/strong><\/h4><p style=\"text-align: justify;\">Fleuve Ogoou\u00e9, S\u00e9diment, M\u00e9taux traces, indicateurs g\u00e9ochimiques, Biodiversit\u00e9 microbienne, Mangroves.<\/p><h4>\u00a0<\/h4><h4 style=\"text-align: justify;\"><strong>Composition of the jury\u00a0<\/strong><\/h4><ul style=\"text-align: justify;\"><li style=\"text-align: justify;\"><p><strong>M. Nicolas Marmier<\/strong>, Professeur des universit\u00e9s, Universit\u00e9 C\u00f4te d&#8217;Azur (France), Rapporteur,<\/p><\/li><li style=\"text-align: justify;\"><p><strong>M. Olivier Gros<\/strong>, Professeur des universit\u00e9s, Universit\u00e9 de Antilles (France), Rapporteur,<\/p><\/li><li style=\"text-align: justify;\"><p><strong>M. Alain Dolla<\/strong>, Directeur de recherche, CNRS (France), Examinateur,<\/p><\/li><li style=\"text-align: justify;\"><p><strong>M. Louis-Cl\u00e9ment Obame Engonga<\/strong>, Professeur des universit\u00e9s, Universit\u00e9 des Sciences et Techniques de Masuku (Gabon), Examinateur,<\/p><\/li><li style=\"text-align: justify;\"><p><strong>Mme Isabelle Navarro<\/strong>, Charg\u00e9e de recherche, IRD (France), Examinatrice,<\/p><\/li><li style=\"text-align: justify;\"><p><strong>Mme Estelle Dumont<\/strong>, Ma\u00eetresse assistante Universit\u00e9 des Sciences et Techniques de Masuku (Gabon), Co-encadrante de th\u00e8se,<\/p><\/li><li style=\"text-align: justify;\"><p><strong>M. Joseph Privat Ondo<\/strong>, Ma\u00eetre de conf\u00e9rences-HDR, Universit\u00e9 des Sciences et Techniques de Masuku (Gabon), Codirecteur de th\u00e8se,<\/p><\/li><li><p style=\"text-align: justify;\"><strong>M. St\u00e9phane Mounier<\/strong>, Ma\u00eetre de conf\u00e9rences-HDR, Universit\u00e9 de Toulon (France), Directeur de th\u00e8se.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecbd37b e-flex e-con-boxed e-con e-parent\" data-id=\"ecbd37b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36e0c0a elementor-widget elementor-widget-image\" data-id=\"36e0c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.mio.osupytheas.fr\/wp-content\/uploads\/2026\/07\/Eleonord.jpeg\" class=\"attachment-large size-large wp-image-29223\" alt=\"\" srcset=\"https:\/\/www.mio.osupytheas.fr\/wp-content\/uploads\/2026\/07\/Eleonord.jpeg 800w, https:\/\/www.mio.osupytheas.fr\/wp-content\/uploads\/2026\/07\/Eleonord-300x300.jpeg 300w, https:\/\/www.mio.osupytheas.fr\/wp-content\/uploads\/2026\/07\/Eleonord-150x150.jpeg 150w, https:\/\/www.mio.osupytheas.fr\/wp-content\/uploads\/2026\/07\/Eleonord-768x768.jpeg 768w, https:\/\/www.mio.osupytheas.fr\/wp-content\/uploads\/2026\/07\/Eleonord-12x12.jpeg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b50aad7 e-flex e-con-boxed e-con e-parent\" data-id=\"b50aad7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e820332 elementor-widget elementor-widget-text-editor\" data-id=\"e820332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><em>Credit photo : Eleonord Mayissah Moungues<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Eleonord Mayissah Moungues (Universit\u00e9 des Sciences et Techniques de Masuku USTM Gabo &#8211; MIO Universit\u00e9 de Toulon) soutiendra sa th\u00e8se de doctorat le Vendredi 17 juillet 2026 \u00e0 14h00 \u00e0 [&hellip;]<\/p>\n","protected":false},"author":319,"featured_media":29229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,1,26],"tags":[],"class_list":["post-29214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualites","category-theses"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/posts\/29214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/users\/319"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/comments?post=29214"}],"version-history":[{"count":12,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/posts\/29214\/revisions"}],"predecessor-version":[{"id":29228,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/posts\/29214\/revisions\/29228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/media\/29229"}],"wp:attachment":[{"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/media?parent=29214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/categories?post=29214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mio.osupytheas.fr\/en\/wp-json\/wp\/v2\/tags?post=29214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}