{"id":26185,"date":"2026-05-06T19:12:10","date_gmt":"2026-05-06T17:12:10","guid":{"rendered":"https:\/\/www.mio.osupytheas.fr\/?post_type=appel_offre&#038;p=26185"},"modified":"2026-05-06T19:12:10","modified_gmt":"2026-05-06T17:12:10","slug":"appel-a-candidatures-contrat-doctoral-president-item-im2b","status":"publish","type":"appel_offre","link":"https:\/\/www.mio.osupytheas.fr\/fr\/appel_offre\/appel-a-candidatures-contrat-doctoral-president-item-im2b\/","title":{"rendered":"Appel \u00e0 candidatures &#8211; Contrat doctoral Pr\u00e9sident ITEM \/ IM2B"},"content":{"rendered":"<p style=\"text-align: justify;\">Date limite de d\u00e9p\u00f4t des candidatures : <strong>16 juin 2026 &#8211; 14h00<\/strong>.<\/p>\r\n<p style=\"text-align: justify;\">Les instituts ITEM et IM2B ( Institut microbiologie, bio\u00e9nergies et biotechnologie) lancent un appel \u00e0 candidatures pour une th\u00e8se men\u00e9e \u00e0 l&#8217;interface entre microbiologie et environnement. Les candidatures seront port\u00e9es par un membre d&#8217;ITEM et un membre d&#8217;IM2B, issus de deux laboratoires diff\u00e9rents (instructions et formulaire de candidature en lien de t\u00e9l\u00e9chargement ).<\/p>\r\n<p style=\"text-align: justify;\">Cet appel \u00e0 candidatures s&#8217;inscrit dans le cadre de la formation doctorale d&#8217;amU, plus pr\u00e9cis\u00e9ment au sein d&#8217;au moins l&#8217;une des \u00e9coles doctorales suivantes ED67, ED250, ED251, ED355, ED372, ED658 or ED659. Le laur\u00e9at sera recrut\u00e9 en tant que doctorant \u00e0 temps plein pour une dur\u00e9e de 3 ans, \u00e0 compter du 1er octobre 2026.<\/p>\r\n<p style=\"text-align: justify;\"><a href=\"https:\/\/filesender.renater.fr\/?s=download&amp;token=e36b6d7d-6c90-4653-8aa7-96430e5ad2a9\" target=\"_blank\" rel=\"noopener\">La note de cadrage ainsi que le formulaire de r\u00e9ponse sont t\u00e9l\u00e9chargeables<\/a> en ligne.<\/p>\r\n<p style=\"text-align: justify;\">Les candidatures (projet et candidat associ\u00e9s dans un m\u00eame dossier) doivent \u00eatre adress\u00e9es avant le<strong> 16 juin 2026 &#8211; <\/strong><strong>14h00<\/strong>, \u00e0 <a href=\"mailto:sophie.pekar@univ-amu.fr\" target=\"_blank\" rel=\"noopener\">sophie.pekar@univ-amu.fr<\/a> et <a href=\"mailto:agnes.kammoun@univ-amu.fr\" target=\"_blank\" rel=\"noopener\">agnes.kammoun@univ-amu.fr<\/a>.<\/p>","protected":false},"parent":0,"template":"","categorie":[31],"class_list":["post-26185","appel_offre","type-appel_offre","status-publish","hentry"],"acf":{"date_limite":"20260616","id_old":""},"_links":{"self":[{"href":"https:\/\/www.mio.osupytheas.fr\/fr\/wp-json\/wp\/v2\/appel_offre\/26185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mio.osupytheas.fr\/fr\/wp-json\/wp\/v2\/appel_offre"}],"about":[{"href":"https:\/\/www.mio.osupytheas.fr\/fr\/wp-json\/wp\/v2\/types\/appel_offre"}],"wp:attachment":[{"href":"https:\/\/www.mio.osupytheas.fr\/fr\/wp-json\/wp\/v2\/media?parent=26185"}],"wp:term":[{"taxonomy":"categorie","embeddable":true,"href":"https:\/\/www.mio.osupytheas.fr\/fr\/wp-json\/wp\/v2\/categorie?post=26185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}